{"id":1060,"date":"2021-03-29T14:03:01","date_gmt":"2021-03-29T11:03:01","guid":{"rendered":"https:\/\/qendwan.com\/?page_id=1060"},"modified":"2025-10-27T23:57:52","modified_gmt":"2025-10-27T20:57:52","slug":"%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa","status":"publish","type":"page","link":"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/","title":{"rendered":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a"},"content":{"rendered":"<div class=\"banner has-hover has-parallax\" id=\"banner-107658685\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-3\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill\"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-185312114\" class=\"text-box banner-layer x50 md-x50 lg-x50 y80 md-y80 lg-y80 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-1384327063\" class=\"text\">\n\t\t\n\n<h1 class=\"lead\">\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0625\u0639\u0644\u0627\u0646\u0627\u062a<\/h1>\n\t\t\n<style>\n#text-1384327063 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-185312114 {\n  width: 60%;\n}\n#text-box-185312114 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-107658685 {\n  padding-top: 350px;\n}\n#banner-107658685 .bg.bg-loaded {\n  background-image: url(http:\/\/qendwan.com\/wp-content\/uploads\/brd_portfolio-1400x384.jpg);\n}\n#banner-107658685 .overlay {\n  background-color: rgba(0, 0, 0, 0.49);\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section\" id=\"section_1096775727\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1642314278\">\n\n\n\t<div id=\"col-289791296\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1248179650\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"384\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/media_banner.jpg\" class=\"attachment-large size-large\" alt=\"\u0627\u0644\u062f\u0639\u0627\u064a\u0629 \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\" srcset=\"http:\/\/qendwan.com\/wp-content\/uploads\/media_banner.jpg 1089w, http:\/\/qendwan.com\/wp-content\/uploads\/media_banner-800x301.jpg 800w, http:\/\/qendwan.com\/wp-content\/uploads\/media_banner-768x289.jpg 768w, http:\/\/qendwan.com\/wp-content\/uploads\/media_banner-600x226.jpg 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1248179650 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"for_h2_heading\">\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0625\u0639\u0644\u0627\u0646\u0627\u062a<br \/>\n<\/h2>\n<p>\u062a\u062e\u064a\u0644 \u0627\u0646\u0647 \u0628\u0627\u0645\u0643\u0627\u0646 \u0627\u0644\u0632\u0648\u0627\u0631 \u0623\u0646 \u064a\u062a\u0639\u0631\u0641\u0648\u0627 \u0639\u0644\u0649 \u0647\u0648\u064a\u062a\u0643 \u0648\u0627\u0644\u0631\u0624\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0648\u0627\u0644\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0642\u062f\u0645\u0647\u0627 \u0628\u062a\u0641\u0627\u0635\u064a\u0644\u0647\u0627 \u0628\u0645\u062c\u0631\u062f \u0627\u0644\u0645\u0631\u0648\u0631 \u0639\u0644\u064a\u0647\u0627\u060c \u062f\u0639 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0627\u0644\u0625\u0639\u0644\u0627\u0646\u064a\u0629 \u062a\u0642\u0648\u0645 \u0628\u0630\u0644\u0643 \u0644\u062f\u064a\u0643 \u0641\u0631\u0635\u0629 \u0623\u0646 \u062a\u062c\u0630\u0628 \u0627\u0647\u062a\u0645\u0627\u0645 \u0632\u0648\u0627\u0631\u0643 \u0644\u062a\u0627\u0633\u064a\u0633 \u0639\u0644\u0627\u0642\u0627\u062a \u0645\u0639\u0647\u0645.<\/p>\n<div class=\"row\"  id=\"row-1196477361\">\n\n\n\t<div id=\"col-57680362\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1232018891\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"296\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/media_frame.jpg\" class=\"attachment-large size-large\" alt=\"frame\" srcset=\"http:\/\/qendwan.com\/wp-content\/uploads\/media_frame.jpg 296w, http:\/\/qendwan.com\/wp-content\/uploads\/media_frame-280x280.jpg 280w, http:\/\/qendwan.com\/wp-content\/uploads\/media_frame-100x100.jpg 100w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1232018891 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-195365684\" class=\"col medium-8 small-12 large-8 small-col-first\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"for_h2_heading\">\u0627\u0644\u0644\u0648\u062d\u0627\u062a \u0627\u0644\u062b\u0627\u0628\u062a\u0629:<br \/>\n<\/h2>\n<p>\u0627\u0644\u0627\u0647\u062a\u0645\u0627\u0645 \u0628\u0627\u0644\u0644\u0648\u062d\u0627\u062a \u0627\u0644\u062b\u0627\u0628\u062a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0643\u0629 \u0645\u0646 \u0627\u0647\u0645 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u060c \u062d\u064a\u062b \u062a\u0642\u0648\u0645 \u0628\u0627\u0639\u0637\u0627\u0621 \u0627\u0644\u0627\u0646\u0637\u0628\u0627\u0639 \u0627\u0644\u0627\u0648\u0644\u064a \u0644\u0644\u0634\u0631\u0643\u0629 \u0639\u0646\u062f \u0643\u0644 \u0632\u064a\u0627\u0631\u0629 \u064a\u0642\u0648\u0645 \u0628\u0647\u0627 \u0627\u0644\u0632\u0648\u0627\u0631 \u0627\u0648 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0627\u0648 \u0627\u0644\u0645\u0631\u0627\u062c\u0639\u064a\u0646 \u0641\u064a \u062f\u0627\u062e\u0644 \u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0648 \u0627\u0644\u0645\u0624\u0633\u0633\u0629.<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-869950207\">\n\n\n\t<div id=\"col-1519248611\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2046284579\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"296\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/media_roll_up.jpg\" class=\"attachment-large size-large\" alt=\"\u0631\u0648\u0644 \u0627\u0628\" srcset=\"http:\/\/qendwan.com\/wp-content\/uploads\/media_roll_up.jpg 296w, http:\/\/qendwan.com\/wp-content\/uploads\/media_roll_up-280x280.jpg 280w, http:\/\/qendwan.com\/wp-content\/uploads\/media_roll_up-100x100.jpg 100w\" sizes=\"(max-width: 296px) 100vw, 296px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2046284579 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1790838484\" class=\"col medium-8 small-12 large-8 small-col-first\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"for_h2_heading\">\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u062d\u0631\u0643\u0629<br \/>\n<\/h2>\n<p>\u0648\u062a\u0639\u062a\u0628\u0631 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u0641\u064a \u062f\u0627\u062e\u0644 \u0627\u0644\u0645\u0634\u0623\u0629 \u0627\u0648 \u0627\u0644\u062a\u0646\u0642\u0644 \u0628\u0647\u0627 \u0641\u064a \u062e\u0627\u0631\u062c \u0627\u0644\u0634\u0631\u0643\u0629 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0641\u064a \u0627\u0644\u0645\u0639\u0627\u0631\u0636 \u0627\u0648 \u0627\u064a \u062d\u062f\u062b.<\/p>\n<p>\u0646\u0642\u062f\u0645 \u0644\u0643\u0645 \u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0645\u0646\u0627\u0633\u0628 \u0644\u0643\u0627\u0641\u0629 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u062d\u062a\u0627\u062c\u0648\u0646\u0647\u0627 \u0648\u0628\u0623\u0633\u0639\u0627\u0631 \u0645\u0646\u0627\u0633\u0628\u0629<\/p>\n<p>.<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1721410033\">\n\n\n\t<div id=\"col-600469457\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1769216111\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand.jpg\" class=\"attachment-large size-large\" alt=\"\u0627\u0633\u062a\u0627\u0646\u062f \u0645\u0632\u062f\u0648\u062c\" srcset=\"http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand.jpg 800w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-400x400.jpg 400w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-280x280.jpg 280w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-768x768.jpg 768w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-12x12.jpg 12w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-300x300.jpg 300w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-600x600.jpg 600w, http:\/\/qendwan.com\/wp-content\/uploads\/double_side_banner_stand-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1769216111 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-344447114\" class=\"col medium-8 small-12 large-8 small-col-first\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"for_h2_heading\">\u0628\u0646\u0631\u0627\u062a \u0645\u0632\u062f\u0648\u062c\u0629<br \/>\n<\/h2>\n<p style=\"color:#1e73be;\">Double Side Banner Stand\n<\/p>\n<p>\n\u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0627\u0644\u0645\u0632\u062f\u0648\u062c\u0629\u0645\u0641\u064a\u062f\u0629 \u062c\u062f\u0627 \u0641\u064a \u062d\u0627\u0644 \u0648\u0636\u0639\u0647\u0627 \u0641\u064a \u0648\u0633\u0637 \u0627\u0644\u0645\u0631\u0627\u0643\u0632 \u0627\u0648 \u0627\u0644\u0645\u0645\u0631\u0627\u062a \u062d\u064a\u062b \u064a\u0645\u0643\u0646 \u0637\u0628\u0627\u0639\u0629 \u0627\u0644\u0628\u0646\u0631 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u064a \u0645\u0646 \u0627\u0644\u0648\u062c\u0647\u064a\u0646 \u0648\u064a\u062a\u064a\u062d \u0644\u0644\u0632\u0627\u0626\u062d \u0645\u0634\u0627\u0647\u062f\u0629 \u0627\u0644\u0627\u0639\u0644\u0627\u0646 \u0641\u064a \u0643\u0644 \u0627\u0644\u0627\u062a\u062c\u0627\u0647\u0627\u062a<\/p>\n<p>\u0645\u062a\u0627\u062d \u0628\u0645\u0642\u0627\u0633\u0627\u062a \u0645\u062e\u062a\u0644\u0641\u0629<br \/>\n\u0645\u0642\u0627\u0633 (60\u00d7160) \u060c (80\u00d7160) \u060c(80\u00d7180)<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-961006565\">\n\n\n\t<div id=\"col-244402588\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"for_h2_heading\">\u0634\u0627\u0634\u0627\u062a \u0627\u0644\u0639\u0631\u0636 \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629<br \/>\n<\/h2>\n<p>\u062a\u0642\u062f\u0645 \u0634\u0627\u0634\u0627\u062a \u0627\u0644\u0644\u0645\u0633 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0639\u0644\u064a\u0629 \u062a\u062c\u0631\u0628\u0629 \u0645\u0645\u062a\u0639\u0629 \u0648\u0639\u0645\u0644\u064a\u0629 \u0644\u0644\u063a\u0627\u064a\u0629 \u0644\u0639\u0645\u0644\u0627\u0626\u0643\u0645\u060c \u062d\u064a\u062b \u062a\u0639\u062f \u0641\u064a \u0637\u0644\u064a\u0639\u0629 \u0623\u062f\u0648\u0627\u062a \u0627\u0644\u062a\u0641\u0627\u0639\u0644 \u0645\u0639 \u0627\u0644\u0639\u0645\u0644\u0627\u0621..<\/p>\n<p>\u0634\u0627\u0634\u0627\u062a \u0631\u0642\u0645\u064a\u0629 \u062a\u0639\u0645\u0644 \u0628\u0627\u0644\u0644\u0645\u0633 \u0628\u062a\u0635\u0645\u064a\u0645\u0647\u0627 \u0627\u0644\u062c\u0630\u0627\u0628 \u0647\u064a \u0643\u0644 \u0645\u0627 \u062a\u062d\u062a\u0627\u062c\u0647 \u0644\u0644\u0625\u0639\u0644\u0627\u0646 \u0639\u0646 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0648\u062e\u062f\u0645\u0629 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0648\u062c\u0645\u0639 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0627\u0644\u0645\u062d\u062a\u0645\u0644\u064a\u0646 \u0648\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0647\u0627 \u0643\u0646\u0638\u0627\u0645 \u0625\u0631\u0634\u0627\u062f\u064a \u0623\u0648 \u0645\u0639\u0644\u0648\u0645\u0627\u062a\u064a..<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-239772246\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-487536182\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": true,            \"wrapAround\": true,            \"autoPlay\": 4000,            \"pauseAutoPlayOnHover\" : false,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": false,            \"rightToLeft\": true,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/banner01-1-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/banner02-1-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/banner03-1-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/banner04-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1483649564\">\n\n\n\t<div id=\"col-1422445304\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"for_h2_heading\">\u062a\u0635\u0645\u064a\u0645 \u0648\u0637\u0628\u0627\u0639\u0629 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0627\u0644\u0639\u0631\u064a\u0636\u0629<br \/>\n<\/h2>\n<p>\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u062e\u0644\u0641\u064a\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0647\u0627 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629 \u0648\u0627\u0644\u0627\u062d\u062a\u0641\u0627\u0644\u0627\u062a \u0648\u0627\u0644\u062a\u062e\u0631\u062c \u0648\u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0645\u0646\u0627\u0633\u0628\u0627\u062a \u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062f\u0627\u062e\u0644\u064a\u0629 \u0648\u0627\u0644\u0645\u0624\u062a\u0645\u0631\u0627\u062a \u0627\u0644\u062e\u0627\u0631\u062c\u064a\u0629.<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-614331901\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-622770236\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": true,            \"wrapAround\": true,            \"autoPlay\": 4000,            \"pauseAutoPlayOnHover\" : false,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": false,            \"rightToLeft\": true,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/bn1-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/bn2-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/bn3-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/bn4-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/bn5-400x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1909935118\">\n\n\n\t<div id=\"col-162488317\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"for_h2_heading\">\u062a\u0635\u0645\u064a\u0645 \u0648\u0637\u0628\u0627\u0639\u0629 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u0639\u0644\u0642\u0629 (\u0627\u0644\u062b\u0627\u0628\u062a\u0629 \u0648\u0627\u0644\u0645\u062a\u062d\u0631\u0643\u0629)<br \/>\n<\/h2>\n<p>\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u0639\u0644\u0642\u0629 \u0641\u064a \u0627\u0644\u0645\u0631\u0627\u0643\u0632 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0648\u0627\u0644\u0645\u0648\u0644\u0627\u062a \u0648\u0635\u0627\u0644\u0627\u062a \u0627\u0644\u0627\u0644\u0639\u0627\u0628 \u060c \u0633\u0648\u0627\u0621\u0627 \u0643\u0627\u0646\u062a \u0627\u0644\u062b\u0627\u0628\u0629 \u0645\u0646\u0647\u0627 \u0627\u0648 \u0627\u0644\u0645\u062a\u062d\u0631\u0643\u0629 \u0644\u0644\u0645\u0646\u0627\u0633\u0628\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629. <\/p><\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-574467204\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-850238062\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": true,            \"wrapAround\": true,            \"autoPlay\": 4000,            \"pauseAutoPlayOnHover\" : false,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": false,            \"rightToLeft\": true,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/hanging_banner01-320x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/hanging_banner02-320x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/hanging_banner03-320x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/hanging_banner04-320x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 230px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img decoding=\"async\" src=\"http:\/\/qendwan.com\/wp-content\/uploads\/hanging_banner05-320x400.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:250px;\" \/><\/div><\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     <\/div>\n\n\n<a href=\"\/portfolio\/\" target=\"_self\" class=\"button primary\"  >\n  <i class=\"icon-angle-right\" ><\/i>  <span>\u0634\u0627\u0647\u062f \u0628\u0639\u0636 \u0623\u0639\u0645\u0627\u0644\u0646\u0627<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1235838081\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" style=\"margin-bottom:-10px;\"><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(30, 115, 190);\">\u0642\u0627\u0626\u0645\u0629 \u062e\u062f\u0645\u0627\u062a\u0646\u0627 :<\/span><b><\/b><\/h3><\/div>\n\n<div class=\"nav-wrapper\"><ul class=\"nav nav-uppercase nav-vertical nav-line text-left nav-left\"><p class=\"lead shortcode-error text-center\">Sorry, no pages was found<\/p><\/ul><\/div>\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1096775727 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1758493560\">\n\n\n\t<div id=\"col-1219256390\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"message-box relative\" style=\"padding-top:30px;padding-bottom:30px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(169, 197, 219);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row align-middle align-center\"  id=\"row-1154210424\">\n\n\n\t<div id=\"col-314208281\" class=\"col medium-9 small-12 large-9\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2487973815\" class=\"text\">\n\t\t\n\n<h2>\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627 \u0641\u064a \u0627\u064a \u0648\u0642\u062a \u0639\u0628\u0631 \u0627\u0644\u0648\u0627\u062a\u0633 \u0627\u0628\n<\/h2>\n\t\t\n<style>\n#text-2487973815 {\n  color: #013c5e;\n}\n#text-2487973815 > * {\n  color: #013c5e;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1364891362\" class=\"col medium-2 small-12 large-2\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/wa.me\/966506680064\" target=\"_blank\" class=\"button primary is-outline is-small\"  >\n  <i class=\"icon-angle-right\" ><\/i>  <span>\u0631\u0627\u0628\u0637 \u0627\u0644\u0648\u0627\u062a\u0633 \u0627\u0628<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\t<section class=\"section\" id=\"section_2000199642\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<p>\u0627\u0631\u0633\u0644 \u0637\u0644\u0628\u0643 \u0648\u0631\u0642\u0645 \u062c\u0648\u0627\u0644\u0643 \u0648\u0633\u0648\u0641 \u064a\u062a\u0645 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0643\u0645 \u0645\u0646 \u0642\u0628\u0644 \u0627\u0644\u0645\u0648\u0638\u0641 \u0627\u0644\u0645\u062e\u062a\u0635<\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f1763-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/1060#wpcf7-f1763-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/ar\/wp-json\/wp\/v2\/pages\/1060#wpcf7-f1763-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1763\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1763-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Your name<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Mobile<br \/>\n    <span class=\"wpcf7-form-control-wrap your-mobile\"><input type=\"tel\" name=\"your-mobile\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your message (optional)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Submit\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2000199642 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":987,"parent":1052,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"spay_email":"","footnotes":""},"class_list":["post-1060","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a | \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u062a\u0633\u062a\u062e\u062f\u0645 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629<\/title>\n<meta name=\"description\" content=\"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/qendwan.com\/ar\/\u062e\u062f\u0645\u0627\u062a\u0646\u0627\/\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u0628\u0646\u0631\u0627\u062a-\u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a | \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u062a\u0633\u062a\u062e\u062f\u0645 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629\" \/>\n<meta property=\"og:description\" content=\"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/qendwan.com\/ar\/\u062e\u062f\u0645\u0627\u062a\u0646\u0627\/\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u0628\u0646\u0631\u0627\u062a-\u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a\/\" \/>\n<meta property=\"og:site_name\" content=\"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/%d8%af%d9%88%d8%a7%d8%a6%d8%b1-%d8%a7%d9%84%d8%ad%d8%a7%d8%b3%d8%a8-%d9%84%d8%ad%d9%84%d9%88%d9%84-%d9%88%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-Dawaer-Tech-for-design-solution-312452202900629\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T20:57:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/qendwan.com\/wp-content\/uploads\/serv04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/\",\"url\":\"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/\",\"name\":\"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a | \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u062a\u0633\u062a\u062e\u062f\u0645 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629\",\"isPartOf\":{\"@id\":\"http:\/\/qendwan.com\/ar\/#website\"},\"datePublished\":\"2021-03-29T11:03:01+00:00\",\"dateModified\":\"2025-10-27T20:57:52+00:00\",\"description\":\"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629.\",\"breadcrumb\":{\"@id\":\"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\/\/qendwan.com\/ar\/%d8%af%d9%88%d8%a7%d8%a6%d8%b1-%d8%a7%d9%84%d8%ad%d8%a7%d8%b3%d8%a8-%d8%ad%d9%84%d9%88%d9%84-%d9%88%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062e\u062f\u0645\u0627\u062a\u0646\u0627\",\"item\":\"https:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/qendwan.com\/ar\/#website\",\"url\":\"http:\/\/qendwan.com\/ar\/\",\"name\":\"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628\",\"description\":\"\u062d\u0644\u0648\u0644 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645\",\"publisher\":{\"@id\":\"http:\/\/qendwan.com\/ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/qendwan.com\/ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/qendwan.com\/ar\/#organization\",\"name\":\"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628 - \u0644\u062d\u0644\u0648\u0644 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645\",\"url\":\"http:\/\/qendwan.com\/ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"http:\/\/qendwan.com\/ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/qendwan.com\/wp-content\/uploads\/2021\/03\/logo_m.jpg\",\"contentUrl\":\"https:\/\/qendwan.com\/wp-content\/uploads\/2021\/03\/logo_m.jpg\",\"width\":199,\"height\":199,\"caption\":\"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628 - \u0644\u062d\u0644\u0648\u0644 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645\"},\"image\":{\"@id\":\"http:\/\/qendwan.com\/ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/\u062f\u0648\u0627\u0626\u0631-\u0627\u0644\u062d\u0627\u0633\u0628-\u0644\u062d\u0644\u0648\u0644-\u0648\u062e\u062f\u0645\u0627\u062a-\u0627\u0644\u062a\u0635\u0645\u064a\u0645-Dawaer-Tech-for-design-solution-312452202900629\/\",\"https:\/\/www.instagram.com\/qendwan\/\",\"https:\/\/www.pinterest.co.uk\/qendwan\/dawaer-tech\/\",\"https:\/\/www.youtube.com\/channel\/UCANUjvfbNe6LXCTn_KmbRRw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a | \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u062a\u0633\u062a\u062e\u062f\u0645 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629","description":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/qendwan.com\/ar\/\u062e\u062f\u0645\u0627\u062a\u0646\u0627\/\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u0628\u0646\u0631\u0627\u062a-\u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a\/","og_locale":"ar_AR","og_type":"article","og_title":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a | \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u062a\u0633\u062a\u062e\u062f\u0645 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629","og_description":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629.","og_url":"http:\/\/qendwan.com\/ar\/\u062e\u062f\u0645\u0627\u062a\u0646\u0627\/\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u0628\u0646\u0631\u0627\u062a-\u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a\/","og_site_name":"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628","article_publisher":"https:\/\/www.facebook.com\/%d8%af%d9%88%d8%a7%d8%a6%d8%b1-%d8%a7%d9%84%d8%ad%d8%a7%d8%b3%d8%a8-%d9%84%d8%ad%d9%84%d9%88%d9%84-%d9%88%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-Dawaer-Tech-for-design-solution-312452202900629\/","article_modified_time":"2025-10-27T20:57:52+00:00","og_image":[{"width":600,"height":491,"url":"http:\/\/qendwan.com\/wp-content\/uploads\/serv04.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/","url":"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/","name":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a | \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u062a\u0633\u062a\u062e\u062f\u0645 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629","isPartOf":{"@id":"http:\/\/qendwan.com\/ar\/#website"},"datePublished":"2021-03-29T11:03:01+00:00","dateModified":"2025-10-27T20:57:52+00:00","description":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u0645\u062a\u0645\u062b\u0644\u0629 \u0641\u064a \u0627\u0644\u0631\u0648\u0644 \u0627\u0648 \u0648\u0627\u0644\u0628\u0648\u0628 \u0627\u0628 \u0648\u0627\u0644\u0627\u0633\u062a\u0627\u0646\u062f\u0627\u062a \u0645\u0646 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u062f\u0627\u062e\u0644 \u0648\u062e\u0627\u0631\u062c \u0627\u0644\u0645\u0634\u0623\u0629.","breadcrumb":{"@id":"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%a8%d9%86%d8%b1%d8%a7%d8%aa-%d9%88%d8%a7%d9%84%d8%a7%d8%b9%d9%84%d8%a7%d9%86%d8%a7%d8%aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/qendwan.com\/ar\/%d8%af%d9%88%d8%a7%d8%a6%d8%b1-%d8%a7%d9%84%d8%ad%d8%a7%d8%b3%d8%a8-%d8%ad%d9%84%d9%88%d9%84-%d9%88%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85\/"},{"@type":"ListItem","position":2,"name":"\u062e\u062f\u0645\u0627\u062a\u0646\u0627","item":"https:\/\/qendwan.com\/ar\/%d8%ae%d8%af%d9%85%d8%a7%d8%aa%d9%86%d8%a7\/"},{"@type":"ListItem","position":3,"name":"\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0628\u0646\u0631\u0627\u062a \u0648\u0627\u0644\u0627\u0639\u0644\u0627\u0646\u0627\u062a"}]},{"@type":"WebSite","@id":"http:\/\/qendwan.com\/ar\/#website","url":"http:\/\/qendwan.com\/ar\/","name":"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628","description":"\u062d\u0644\u0648\u0644 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645","publisher":{"@id":"http:\/\/qendwan.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/qendwan.com\/ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ar"},{"@type":"Organization","@id":"http:\/\/qendwan.com\/ar\/#organization","name":"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628 - \u0644\u062d\u0644\u0648\u0644 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645","url":"http:\/\/qendwan.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"http:\/\/qendwan.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/qendwan.com\/wp-content\/uploads\/2021\/03\/logo_m.jpg","contentUrl":"https:\/\/qendwan.com\/wp-content\/uploads\/2021\/03\/logo_m.jpg","width":199,"height":199,"caption":"\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u062d\u0627\u0633\u0628 - \u0644\u062d\u0644\u0648\u0644 \u0648\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645"},"image":{"@id":"http:\/\/qendwan.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/\u062f\u0648\u0627\u0626\u0631-\u0627\u0644\u062d\u0627\u0633\u0628-\u0644\u062d\u0644\u0648\u0644-\u0648\u062e\u062f\u0645\u0627\u062a-\u0627\u0644\u062a\u0635\u0645\u064a\u0645-Dawaer-Tech-for-design-solution-312452202900629\/","https:\/\/www.instagram.com\/qendwan\/","https:\/\/www.pinterest.co.uk\/qendwan\/dawaer-tech\/","https:\/\/www.youtube.com\/channel\/UCANUjvfbNe6LXCTn_KmbRRw"]}]}},"_links":{"self":[{"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/pages\/1060"}],"collection":[{"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/comments?post=1060"}],"version-history":[{"count":28,"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/pages\/1060\/revisions"}],"predecessor-version":[{"id":7483,"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/pages\/1060\/revisions\/7483"}],"up":[{"embeddable":true,"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/pages\/1052"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/media\/987"}],"wp:attachment":[{"href":"http:\/\/qendwan.com\/ar\/wp-json\/wp\/v2\/media?parent=1060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}